{"id":629,"date":"2014-03-28T16:52:54","date_gmt":"2014-03-28T14:52:54","guid":{"rendered":"http:\/\/mfs-mafa.com\/?page_id=629"},"modified":"2016-04-14T11:16:04","modified_gmt":"2016-04-14T09:16:04","slug":"building-site","status":"publish","type":"page","link":"https:\/\/mfs-mafa.com\/en\/references\/building-site\/","title":{"rendered":"Building site"},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-629 gallery-columns-3 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/1-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/1-300x225.jpg 300w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/1.jpg 552w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/2-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/2-300x225.jpg 300w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/2.jpg 552w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/3-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/3-300x225.jpg 300w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/3.jpg 552w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/4-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/4-300x225.jpg 300w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/4.jpg 552w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/5-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/5-300x225.jpg 300w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/5.jpg 552w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/6-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/6-300x225.jpg 300w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/6.jpg 552w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/7-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/7-300x225.jpg 300w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/7.jpg 552w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/8.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/8-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/8-300x225.jpg 300w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/8.jpg 552w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/9.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/9-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/9-225x300.jpg 225w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/9.jpg 414w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/10.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/10-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/10-225x300.jpg 225w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/10.jpg 414w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/11.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/11-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/11-225x300.jpg 225w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/11.jpg 414w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/12.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/12-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/12-225x300.jpg 225w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/12.jpg 414w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/13.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/13-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/13-225x300.jpg 225w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/13.jpg 414w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/14.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/14-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/14-225x300.jpg 225w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/14.jpg 414w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/1-nggid011-ngg0dyn-0x250-00f0w011c010r110f110r010t010.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/1-nggid011-ngg0dyn-0x250-00f0w011c010r110f110r010t010-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/1-nggid011-ngg0dyn-0x250-00f0w011c010r110f110r010t010-300x225.jpg 300w, https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/1-nggid011-ngg0dyn-0x250-00f0w011c010r110f110r010t010.jpg 333w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/1-nggid0262-ngg0dyn-200x200x90-00f0w010c010r110f110r010t03jpg.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"150\" src=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/1-nggid0262-ngg0dyn-200x200x90-00f0w010c010r110f110r010t03jpg.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":51,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-629","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Building site - Welcome to MFS Maschinenfabrik<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mfs-mafa.com\/en\/references\/building-site\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Building site - Welcome to MFS Maschinenfabrik\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mfs-mafa.com\/en\/references\/building-site\/\" \/>\n<meta property=\"og:site_name\" content=\"Welcome to MFS Maschinenfabrik\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-14T09:16:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/1-300x225.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/references\\\/building-site\\\/\",\"url\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/references\\\/building-site\\\/\",\"name\":\"Building site - Welcome to MFS Maschinenfabrik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/#website\"},\"datePublished\":\"2014-03-28T14:52:54+00:00\",\"dateModified\":\"2016-04-14T09:16:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/references\\\/building-site\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/references\\\/building-site\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/references\\\/building-site\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"References\",\"item\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/references\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Building site\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/\",\"name\":\"MFS Maschinenfabrik GmbH & Co. KG\",\"description\":\"MFS Maschinenfabrik GmbH &amp; Co. KG - Wilhelmshaven\",\"publisher\":{\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/#organization\",\"name\":\"MFS Maschinenfabrik GmbH & Co. KG\",\"url\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/logo-mfs.png\",\"contentUrl\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/logo-mfs.png\",\"width\":190,\"height\":127,\"caption\":\"MFS Maschinenfabrik GmbH & Co. KG\"},\"image\":{\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Building site - Welcome to MFS Maschinenfabrik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mfs-mafa.com\/en\/references\/building-site\/","og_locale":"de_DE","og_type":"article","og_title":"Building site - Welcome to MFS Maschinenfabrik","og_url":"https:\/\/mfs-mafa.com\/en\/references\/building-site\/","og_site_name":"Welcome to MFS Maschinenfabrik","article_modified_time":"2016-04-14T09:16:04+00:00","og_image":[{"url":"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2014\/03\/1-300x225.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mfs-mafa.com\/en\/references\/building-site\/","url":"https:\/\/mfs-mafa.com\/en\/references\/building-site\/","name":"Building site - Welcome to MFS Maschinenfabrik","isPartOf":{"@id":"https:\/\/mfs-mafa.com\/en\/#website"},"datePublished":"2014-03-28T14:52:54+00:00","dateModified":"2016-04-14T09:16:04+00:00","breadcrumb":{"@id":"https:\/\/mfs-mafa.com\/en\/references\/building-site\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mfs-mafa.com\/en\/references\/building-site\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mfs-mafa.com\/en\/references\/building-site\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mfs-mafa.com\/en\/"},{"@type":"ListItem","position":2,"name":"References","item":"https:\/\/mfs-mafa.com\/en\/references\/"},{"@type":"ListItem","position":3,"name":"Building site"}]},{"@type":"WebSite","@id":"https:\/\/mfs-mafa.com\/en\/#website","url":"https:\/\/mfs-mafa.com\/en\/","name":"MFS Maschinenfabrik GmbH & Co. KG","description":"MFS Maschinenfabrik GmbH &amp; Co. KG - Wilhelmshaven","publisher":{"@id":"https:\/\/mfs-mafa.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mfs-mafa.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mfs-mafa.com\/en\/#organization","name":"MFS Maschinenfabrik GmbH & Co. KG","url":"https:\/\/mfs-mafa.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mfs-mafa.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2023\/02\/logo-mfs.png","contentUrl":"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2023\/02\/logo-mfs.png","width":190,"height":127,"caption":"MFS Maschinenfabrik GmbH & Co. KG"},"image":{"@id":"https:\/\/mfs-mafa.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/pages\/629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/comments?post=629"}],"version-history":[{"count":6,"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/pages\/629\/revisions"}],"predecessor-version":[{"id":1368,"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/pages\/629\/revisions\/1368"}],"up":[{"embeddable":true,"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/pages\/51"}],"wp:attachment":[{"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/media?parent=629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}