{"id":128,"date":"2013-11-06T12:43:15","date_gmt":"2013-11-06T11:43:15","guid":{"rendered":"http:\/\/mfs-mafa.com\/?page_id=128"},"modified":"2016-04-07T10:51:09","modified_gmt":"2016-04-07T08:51:09","slug":"news","status":"publish","type":"page","link":"https:\/\/mfs-mafa.com\/en\/news\/","title":{"rendered":"News"},"content":{"rendered":"<h2>This page is under construction.<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>This page is under construction.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-128","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News - Welcome to MFS Maschinenfabrik<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mfs-mafa.com\/en\/news\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News - Welcome to MFS Maschinenfabrik\" \/>\n<meta property=\"og:description\" content=\"This page is under construction.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mfs-mafa.com\/en\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"Welcome to MFS Maschinenfabrik\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-07T08:51:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/news\\\/\",\"url\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/news\\\/\",\"name\":\"News - Welcome to MFS Maschinenfabrik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/#website\"},\"datePublished\":\"2013-11-06T11:43:15+00:00\",\"dateModified\":\"2016-04-07T08:51:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/news\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/news\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/\",\"name\":\"MFS Maschinenfabrik GmbH & Co. KG\",\"description\":\"MFS Maschinenfabrik GmbH &amp; Co. KG - Wilhelmshaven\",\"publisher\":{\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/#organization\",\"name\":\"MFS Maschinenfabrik GmbH & Co. KG\",\"url\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/logo-mfs.png\",\"contentUrl\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/02\\\/logo-mfs.png\",\"width\":190,\"height\":127,\"caption\":\"MFS Maschinenfabrik GmbH & Co. KG\"},\"image\":{\"@id\":\"https:\\\/\\\/mfs-mafa.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News - Welcome to MFS Maschinenfabrik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mfs-mafa.com\/en\/news\/","og_locale":"de_DE","og_type":"article","og_title":"News - Welcome to MFS Maschinenfabrik","og_description":"This page is under construction.","og_url":"https:\/\/mfs-mafa.com\/en\/news\/","og_site_name":"Welcome to MFS Maschinenfabrik","article_modified_time":"2016-04-07T08:51:09+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mfs-mafa.com\/en\/news\/","url":"https:\/\/mfs-mafa.com\/en\/news\/","name":"News - Welcome to MFS Maschinenfabrik","isPartOf":{"@id":"https:\/\/mfs-mafa.com\/en\/#website"},"datePublished":"2013-11-06T11:43:15+00:00","dateModified":"2016-04-07T08:51:09+00:00","breadcrumb":{"@id":"https:\/\/mfs-mafa.com\/en\/news\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mfs-mafa.com\/en\/news\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mfs-mafa.com\/en\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mfs-mafa.com\/en\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/mfs-mafa.com\/en\/#website","url":"https:\/\/mfs-mafa.com\/en\/","name":"MFS Maschinenfabrik GmbH & Co. KG","description":"MFS Maschinenfabrik GmbH &amp; Co. KG - Wilhelmshaven","publisher":{"@id":"https:\/\/mfs-mafa.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mfs-mafa.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mfs-mafa.com\/en\/#organization","name":"MFS Maschinenfabrik GmbH & Co. KG","url":"https:\/\/mfs-mafa.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mfs-mafa.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2023\/02\/logo-mfs.png","contentUrl":"https:\/\/mfs-mafa.com\/en\/wp-content\/uploads\/sites\/2\/2023\/02\/logo-mfs.png","width":190,"height":127,"caption":"MFS Maschinenfabrik GmbH & Co. KG"},"image":{"@id":"https:\/\/mfs-mafa.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/pages\/128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/comments?post=128"}],"version-history":[{"count":2,"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/pages\/128\/revisions"}],"predecessor-version":[{"id":1237,"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/pages\/128\/revisions\/1237"}],"wp:attachment":[{"href":"https:\/\/mfs-mafa.com\/en\/wp-json\/wp\/v2\/media?parent=128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}